{"id":23050,"date":"2024-04-24T14:36:10","date_gmt":"2024-04-24T09:06:10","guid":{"rendered":"https:\/\/asicmarketplace.com\/?post_type=product&#038;p=23050"},"modified":"2026-07-08T09:14:57","modified_gmt":"2026-07-08T03:44:57","slug":"canaan-avalon-nano-3-home-miner-4","status":"publish","type":"product","link":"https:\/\/asicmarketplace.com\/de\/product\/canaan-avalon-nano-3-home-miner-4th\/","title":{"rendered":"Canaan Avalon Nano 3 Home Miner (4 TH\/s)"},"content":{"rendered":"<h3 style=\"text-align: center;\">\u00dcBERBLICK<\/h3>\n<p style=\"text-align: center;\" class=\"translation-block\"><strong>Der Avalon Nano 3 <\/strong>(4Th) ist ein tragbarer, kompakter Miner mit einer Hashrate von<strong> 4 Th\/s<\/strong> bei einer Leistungsaufnahme von <strong>140 W<\/strong>.<\/p>\n<h3 style=\"text-align: center;\">SPEZIFIKATIONEN<\/h3>\n<table class=\"table table-striped\">\n<tbody>\n<tr>\n<th scope=\"row\">Hersteller<\/th>\n<td>Kanaan<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Modell<\/th>\n<td>Avalon Nano 3 (4. Gen.)<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Gewicht<\/th>\n<td>725g<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Ger\u00e4uschpegel<\/th>\n<td>33-36 dB<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Spannung<\/th>\n<td>28V<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Effizienz<\/th>\n<td>29j\/Th<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Strom<\/th>\n<td>140W<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Hertz<\/th>\n<td>50\/60Hz<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Gr\u00f6\u00dfe<\/th>\n<td>205 x 115 x 57mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Temperatur<\/th>\n<td>40-60\u00b0C<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Luftfeuchtigkeit<\/th>\n<td>0-90%<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"\u00dcBERBLICK Der Avalon Nano 3 (4Th) ist ein tragbarer kleiner Heater mit einer Hashrate von 4 Th\/s bei einer Leistungsaufnahme von 140 W. TECHNISCHE DATEN Hersteller Canaan Modell Avalon Nano 3\u00a0 (4Th) Gewicht 725 g Ger\u00e4uschpegel 33\u201336 dB Spannung 28 V Wirkungsgrad 29 J\/Th Leistung 140 W Frequenz 50\/60 Hz Abmessungen 205 \u00d7 115 \u00d7 57 mm Temperatur 40\u201360 \u00b0C Luftfeuchtigkeit 0\u201390 %","protected":false},"featured_media":23082,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"product_brand":[505,508],"product_cat":[83],"product_tag":[],"class_list":["post-23050","product","type-product","status-publish","has-post-thumbnail","product_brand-asic-miners","product_brand-home-miners","product_cat-canaan-avalon","collection-bitcoin-miners","first","instock","featured","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/product\/23050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/comments?post=23050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/media\/23082"}],"wp:attachment":[{"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/media?parent=23050"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/product_brand?post=23050"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/product_cat?post=23050"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/asicmarketplace.com\/de\/wp-json\/wp\/v2\/product_tag?post=23050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}