{"id":10189,"date":"2021-09-11T14:37:01","date_gmt":"2021-09-11T14:37:01","guid":{"rendered":"https:\/\/asicmarketplace.com\/?post_type=product&#038;p=10189"},"modified":"2026-07-08T09:14:47","modified_gmt":"2026-07-08T03:44:47","slug":"bitmain-antminer-d7-1286gh","status":"publish","type":"product","link":"https:\/\/asicmarketplace.com\/es\/product\/bitmain-antminer-d7-1286gh\/","title":{"rendered":"Bitmain Antminer D7 (1286Gh)"},"content":{"rendered":"<h3 style=\"text-align: center;\">RESUMEN<\/h3>\n<p style=\"text-align: center;\" class=\"translation-block\">Bitmain <strong>Antminer D7<\/strong> (1286Gh) de algoritmo <strong>X11<\/strong> con potencia de hashing de <strong>1286Gh\/s<\/strong> con consumo de energ\u00eda de <strong>3148W.<\/strong><\/p>\n<h3 style=\"text-align: center;\">ESPECIFICACIONES<\/h3>\n<table>\n<tbody>\n<tr>\n<th scope=\"row\">Fabricante<\/th>\n<td>Bitmain<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Modelo<\/th>\n<td>Antminer D7 (1286Gh)<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Tambi\u00e9n conocido como<\/th>\n<td>Antminer D7 1.286Th<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Liberar<\/th>\n<td>Octubre 2021<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Tama\u00f1o<\/th>\n<td>400 x 195 x 290 mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Peso<\/th>\n<td>14200g<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Nivel de ruido<\/th>\n<td>75 dB<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Ventilador(es)<\/th>\n<td>4<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Potencia<\/th>\n<td>3148W<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Voltaje<\/th>\n<td>12V<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Interfaz - Ethernet<\/th>\n<td>Ethernet<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Temperatura<\/th>\n<td>5 - 45 \u00b0C<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Humedad<\/th>\n<td>5 - 95 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><!-- .elementskit-card END --><\/p>","protected":false},"excerpt":{"rendered":"DESCRIPCI\u00d3N Bitmain Antminer D7 (1286Gh) de algoritmo X11 con una potencia de mineria de 1286Gh\/s a un consumo de energ\u00eda de 3148W. ESPECIFICACI\u00d3N Fabricante Bitmain Modelo Antminer D7 (1286Gh) Tambi\u00e9n conocido como Antminer D7 1.286Th Lanzamiento Octubre 2021 Tama\u00f1o 400 x 195 x 290mm Peso 14200g Nivel de ruido 75db Ventilador(es) 4 Potencia 3148W Voltaje 12V Interfaz Ethernet Temperatura 5 &#8211;&#8230; <a class=\"view-article\" href=\"https:\/\/asicmarketplace.com\/es\/product\/bitmain-antminer-d7-1286gh\/\">Ver art\u00edculo<\/a>","protected":false},"featured_media":16098,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"product_brand":[505],"product_cat":[15],"product_tag":[],"class_list":["post-10189","product","type-product","status-publish","has-post-thumbnail","product_brand-asic-miners","product_cat-bitmain","collection-dash-miners","first","outofstock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product\/10189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/comments?post=10189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media\/16098"}],"wp:attachment":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media?parent=10189"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_brand?post=10189"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_cat?post=10189"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_tag?post=10189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}