{"id":2673,"date":"2021-02-27T19:32:52","date_gmt":"2021-02-27T19:32:52","guid":{"rendered":"https:\/\/asicmarketplace.com\/?post_type=product&#038;p=2673"},"modified":"2026-07-08T09:14:51","modified_gmt":"2026-07-08T03:44:51","slug":"goldshell-kd2-kadena-miner-6-4-th-s","status":"publish","type":"product","link":"https:\/\/asicmarketplace.com\/es\/product\/goldshell-kd2-kadena-miner-6-4-th-s\/","title":{"rendered":"Goldshell KD2 - Kadena Miner (6.4Th)"},"content":{"rendered":"<h3 style=\"text-align: center;\">RESUMEN<\/h3>\n<p style=\"text-align: center;\" class=\"translation-block\"><strong>Goldshell KD2<\/strong> (6.4Th) de algoritmo <strong>Kadena<\/strong> con potencia de hashing de <strong>6.4Th\/s<\/strong> con consumo de energ\u00eda de <strong>830W.<\/strong><\/p>\n<h3 style=\"text-align: center;\">ESPECIFICACIONES<\/h3>\n<table>\n<tbody>\n<tr>\n<th scope=\"row\">Fabricante<\/th>\n<td>Goldshell<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Modelo<\/th>\n<td>KD2<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Tambi\u00e9n conocido como<\/th>\n<td>minero KD2 Kadena<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Liberar<\/th>\n<td>Marzo de 2021<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Tama\u00f1o<\/th>\n<td>200 x 264 x 290mm<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Peso<\/th>\n<td>7300g<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Nivel de ruido<\/th>\n<td>55 dB<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Ventilador(es)<\/th>\n<td>2<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Potencia<\/th>\n<td>830W<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Voltaje<\/th>\n<td>176~264V<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Interfaz - Ethernet<\/th>\n<td>Ethernet<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Temperatura<\/th>\n<td>5 - 45 \u00b0C<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Humedad<\/th>\n<td>5 - 95 %<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><!-- .elementskit-card END --><\/p>","protected":false},"excerpt":{"rendered":"INFORMACI\u00d3N Goldshell KD2 (6.4Th) del algoritmo Kadena con una potencia de c\u00e1lculo de 6.4Th\/s y un consumo de energ\u00eda de 830W. ESPECIFICACIONES Fabricante Goldshell Modelo KD2 Tambi\u00e9n conocido como minero Kadena KD2 Lanzamiento Marzo 2021 Tama\u00f1o 200 x 264 x 290mm Peso 7300g Nivel de ruido 55db Ventilador(es) 2 Potencia 830W Voltaje 176~264V Interfaz Ethernet Temperatura 5 &#8211; 45 \u00b0C Humedad... <a class=\"view-article\" href=\"https:\/\/asicmarketplace.com\/es\/product\/goldshell-kd2-kadena-miner-6-4-th-s\/\">Ver art\u00edculo<\/a>","protected":false},"featured_media":15983,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"product_brand":[505],"product_cat":[78],"product_tag":[],"class_list":["post-2673","product","type-product","status-publish","has-post-thumbnail","product_brand-asic-miners","product_cat-goldshell","collection-kadena-miners","first","outofstock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/comments?post=2673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media\/15983"}],"wp:attachment":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media?parent=2673"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_brand?post=2673"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_cat?post=2673"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_tag?post=2673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}