{"id":35040,"date":"2025-10-11T12:22:38","date_gmt":"2025-10-11T06:52:38","guid":{"rendered":"https:\/\/asicmarketplace.com\/?post_type=product&#038;p=35040"},"modified":"2026-07-09T14:11:22","modified_gmt":"2026-07-09T08:41:22","slug":"bomba-de-circulacion-de-radiador-de-refrigeracion-por-agua-de-amplificador","status":"publish","type":"product","link":"https:\/\/asicmarketplace.com\/es\/product\/amp-water-cooling-radiator-circulation-pump\/","title":{"rendered":"Bomba de Circulaci\u00f3n de Radiador de Agua AMP 24V Tanque Refrigerador"},"content":{"rendered":"<p>El Sistema de Refrigeraci\u00f3n por Agua de Doble Bomba es una bomba de agua sin escobillas de CC de alto rendimiento dise\u00f1ada para la refrigeraci\u00f3n de mineros ASIC y la gesti\u00f3n t\u00e9rmica de servidores. Su dise\u00f1o de doble bomba de bajo ruido ofrece el doble de potencia de refrigeraci\u00f3n, caudal y presi\u00f3n de elevaci\u00f3n en un formato compacto, proporcionando una disipaci\u00f3n de calor superior y estabilidad del sistema. Incluso si una bomba falla, la otra contin\u00faa funcionando, evitando el sobrecalentamiento, da\u00f1os en el hardware y tiempo de inactividad de la miner\u00eda. Dise\u00f1ado para operaciones de miner\u00eda de criptomonedas 24\/7, garantiza la m\u00e1xima eficiencia de refrigeraci\u00f3n, fiabilidad y rendimiento a largo plazo.<\/p>\n<p>Este sistema viene con una configuraci\u00f3n de bomba dual dise\u00f1ada para ofrecer un rendimiento potente y confiable. Fabricado con materiales duraderos de primera calidad, garantiza estabilidad a largo plazo y un funcionamiento suave. Con protecci\u00f3n inteligente contra escasez de agua, monitorea y controla autom\u00e1ticamente las funciones de arranque y parada para garantizar un uso seguro y eficiente.<\/p>\n<h4>Especificaciones<\/h4>\n<table class=\"table table-striped\">\n<tbody>\n<tr>\n<th scope=\"row\">Voltaje de operaci\u00f3n<\/th>\n<td>CC24V<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Cabeza m\u00e1xima<\/th>\n<td>38\u00b11M<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Potencia nominal<\/th>\n<td>163.2W<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Sellado<\/th>\n<td>&lt;0.2MPa<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Flujo M\u00e1ximo<\/th>\n<td>25\u00b11L\/min<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Corriente Nominal<\/th>\n<td>6.8\u00b15%A<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Formulario de interfaz<\/th>\n<td>Puerto roscado G1\/2 (4 puntos)<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">ruido<\/th>\n<td>50 dB<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Dise\u00f1a Vida<\/th>\n<td>30,000 horas<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Material de la bomba<\/th>\n<td>Aleaci\u00f3n de aluminio + PC + POM<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Principio de funcionamiento<\/th>\n<td>Bomba centr\u00edfuga<\/td>\n<\/tr>\n<tr>\n<th scope=\"row\">Observaciones<\/th>\n<td>\u00a0Bomba de agua sin escobillas trif\u00e1sica de corriente continua<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"El sistema de refrigeraci\u00f3n por agua de doble bomba es una bomba de agua DC sin escobillas de alto rendimiento dise\u00f1ada para la refrigeraci\u00f3n de mineros ASIC y la gesti\u00f3n t\u00e9rmica de servidores. Su dise\u00f1o de doble bomba de bajo ruido ofrece el doble de potencia de refrigeraci\u00f3n, caudal y altura de elevaci\u00f3n en un formato compacto, proporcionando una disipaci\u00f3n de calor superior y estabilidad del sistema. Incluso si una bomba falla, el&#8230; <a class=\"view-article\" href=\"https:\/\/asicmarketplace.com\/es\/product\/amp-water-cooling-radiator-circulation-pump\/\">Ver art\u00edculo<\/a>","protected":false},"featured_media":35042,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"product_brand":[506],"product_cat":[511],"product_tag":[],"class_list":["post-35040","product","type-product","status-publish","has-post-thumbnail","product_brand-accessories","product_cat-hydro-cooling","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product\/35040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/comments?post=35040"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media\/35042"}],"wp:attachment":[{"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/media?parent=35040"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_brand?post=35040"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_cat?post=35040"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/asicmarketplace.com\/es\/wp-json\/wp\/v2\/product_tag?post=35040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}